{"id":151,"count":19,"description":"","link":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/","name":"\u03a0\u0391\u039d\u0399\u0391","slug":"pania","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u03a0\u0391\u039d\u0399\u0391 Archives - Alpha Omega Car Detailing<\/title>\n<meta name=\"description\" content=\"\u039c\u03b9\u03ba\u03c1\u03bf\u0390\u03bd\u03b5\u03c2 \u03ba\u03bb\u03b5\u03b9\u03c3\u03c4\u03ae\u03c2 \u03c0\u03bb\u03ad\u03be\u03b7\u03c2, waffle weave &amp; suede \u03b3\u03b9\u03b1 \u03b1\u03bb\u03bf\u03b9\u03c6\u03ad\u03c2, polish &amp; \u03b3\u03c5\u03ac\u03bb\u03b9\u03c3\u03bc\u03b1 \u03c4\u03b6\u03b1\u03bc\u03b9\u03ce\u03bd. Premium \u03c0\u03b1\u03bd\u03b9\u03ac detailing \u03bc\u03b5 \u03b5\u03b3\u03b3\u03c5\u03b7\u03bc\u03ad\u03bd\u03b7 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1. \u0394\u03b5\u03c2 \u03c4\u03b1!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u03a0\u0391\u039d\u0399\u0391 Archives - Alpha Omega Car Detailing\" \/>\n<meta property=\"og:description\" content=\"\u039c\u03b9\u03ba\u03c1\u03bf\u0390\u03bd\u03b5\u03c2 \u03ba\u03bb\u03b5\u03b9\u03c3\u03c4\u03ae\u03c2 \u03c0\u03bb\u03ad\u03be\u03b7\u03c2, waffle weave &amp; suede \u03b3\u03b9\u03b1 \u03b1\u03bb\u03bf\u03b9\u03c6\u03ad\u03c2, polish &amp; \u03b3\u03c5\u03ac\u03bb\u03b9\u03c3\u03bc\u03b1 \u03c4\u03b6\u03b1\u03bc\u03b9\u03ce\u03bd. Premium \u03c0\u03b1\u03bd\u03b9\u03ac detailing \u03bc\u03b5 \u03b5\u03b3\u03b3\u03c5\u03b7\u03bc\u03ad\u03bd\u03b7 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1. \u0394\u03b5\u03c2 \u03c4\u03b1!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/\" \/>\n<meta property=\"og:site_name\" content=\"Alpha Omega Car Detailing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/product-category\\\/pania\\\/\",\"url\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/product-category\\\/pania\\\/\",\"name\":\"\u03a0\u0391\u039d\u0399\u0391 Archives - Alpha Omega Car Detailing\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/#website\"},\"description\":\"\u039c\u03b9\u03ba\u03c1\u03bf\u0390\u03bd\u03b5\u03c2 \u03ba\u03bb\u03b5\u03b9\u03c3\u03c4\u03ae\u03c2 \u03c0\u03bb\u03ad\u03be\u03b7\u03c2, waffle weave & suede \u03b3\u03b9\u03b1 \u03b1\u03bb\u03bf\u03b9\u03c6\u03ad\u03c2, polish & \u03b3\u03c5\u03ac\u03bb\u03b9\u03c3\u03bc\u03b1 \u03c4\u03b6\u03b1\u03bc\u03b9\u03ce\u03bd. Premium \u03c0\u03b1\u03bd\u03b9\u03ac detailing \u03bc\u03b5 \u03b5\u03b3\u03b3\u03c5\u03b7\u03bc\u03ad\u03bd\u03b7 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1. \u0394\u03b5\u03c2 \u03c4\u03b1!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/product-category\\\/pania\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/product-category\\\/pania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u03a0\u0391\u039d\u0399\u0391\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/\",\"name\":\"Alpha Omega Car Detailing\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/#organization\",\"name\":\"Alpha Omega Car Detailing\",\"url\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/alphaomega-logo-blh.svg\",\"contentUrl\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/alphaomega-logo-blh.svg\",\"width\":2736,\"height\":454,\"caption\":\"Alpha Omega Car Detailing\"},\"image\":{\"@id\":\"https:\\\/\\\/alphaomegadetailing.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u03a0\u0391\u039d\u0399\u0391 Archives - Alpha Omega Car Detailing","description":"\u039c\u03b9\u03ba\u03c1\u03bf\u0390\u03bd\u03b5\u03c2 \u03ba\u03bb\u03b5\u03b9\u03c3\u03c4\u03ae\u03c2 \u03c0\u03bb\u03ad\u03be\u03b7\u03c2, waffle weave & suede \u03b3\u03b9\u03b1 \u03b1\u03bb\u03bf\u03b9\u03c6\u03ad\u03c2, polish & \u03b3\u03c5\u03ac\u03bb\u03b9\u03c3\u03bc\u03b1 \u03c4\u03b6\u03b1\u03bc\u03b9\u03ce\u03bd. Premium \u03c0\u03b1\u03bd\u03b9\u03ac detailing \u03bc\u03b5 \u03b5\u03b3\u03b3\u03c5\u03b7\u03bc\u03ad\u03bd\u03b7 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1. \u0394\u03b5\u03c2 \u03c4\u03b1!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/","og_locale":"en_US","og_type":"article","og_title":"\u03a0\u0391\u039d\u0399\u0391 Archives - Alpha Omega Car Detailing","og_description":"\u039c\u03b9\u03ba\u03c1\u03bf\u0390\u03bd\u03b5\u03c2 \u03ba\u03bb\u03b5\u03b9\u03c3\u03c4\u03ae\u03c2 \u03c0\u03bb\u03ad\u03be\u03b7\u03c2, waffle weave & suede \u03b3\u03b9\u03b1 \u03b1\u03bb\u03bf\u03b9\u03c6\u03ad\u03c2, polish & \u03b3\u03c5\u03ac\u03bb\u03b9\u03c3\u03bc\u03b1 \u03c4\u03b6\u03b1\u03bc\u03b9\u03ce\u03bd. Premium \u03c0\u03b1\u03bd\u03b9\u03ac detailing \u03bc\u03b5 \u03b5\u03b3\u03b3\u03c5\u03b7\u03bc\u03ad\u03bd\u03b7 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1. \u0394\u03b5\u03c2 \u03c4\u03b1!","og_url":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/","og_site_name":"Alpha Omega Car Detailing","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/","url":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/","name":"\u03a0\u0391\u039d\u0399\u0391 Archives - Alpha Omega Car Detailing","isPartOf":{"@id":"https:\/\/alphaomegadetailing.gr\/en\/#website"},"description":"\u039c\u03b9\u03ba\u03c1\u03bf\u0390\u03bd\u03b5\u03c2 \u03ba\u03bb\u03b5\u03b9\u03c3\u03c4\u03ae\u03c2 \u03c0\u03bb\u03ad\u03be\u03b7\u03c2, waffle weave & suede \u03b3\u03b9\u03b1 \u03b1\u03bb\u03bf\u03b9\u03c6\u03ad\u03c2, polish & \u03b3\u03c5\u03ac\u03bb\u03b9\u03c3\u03bc\u03b1 \u03c4\u03b6\u03b1\u03bc\u03b9\u03ce\u03bd. Premium \u03c0\u03b1\u03bd\u03b9\u03ac detailing \u03bc\u03b5 \u03b5\u03b3\u03b3\u03c5\u03b7\u03bc\u03ad\u03bd\u03b7 \u03c0\u03bf\u03b9\u03cc\u03c4\u03b7\u03c4\u03b1. \u0394\u03b5\u03c2 \u03c4\u03b1!","breadcrumb":{"@id":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/alphaomegadetailing.gr\/en\/product-category\/pania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alphaomegadetailing.gr\/en\/"},{"@type":"ListItem","position":2,"name":"\u03a0\u0391\u039d\u0399\u0391"}]},{"@type":"WebSite","@id":"https:\/\/alphaomegadetailing.gr\/en\/#website","url":"https:\/\/alphaomegadetailing.gr\/en\/","name":"Alpha Omega Car Detailing","description":"","publisher":{"@id":"https:\/\/alphaomegadetailing.gr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alphaomegadetailing.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alphaomegadetailing.gr\/en\/#organization","name":"Alpha Omega Car Detailing","url":"https:\/\/alphaomegadetailing.gr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alphaomegadetailing.gr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/alphaomegadetailing.gr\/wp-content\/uploads\/2023\/07\/alphaomega-logo-blh.svg","contentUrl":"https:\/\/alphaomegadetailing.gr\/wp-content\/uploads\/2023\/07\/alphaomega-logo-blh.svg","width":2736,"height":454,"caption":"Alpha Omega Car Detailing"},"image":{"@id":"https:\/\/alphaomegadetailing.gr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/alphaomegadetailing.gr\/en\/wp-json\/wp\/v2\/product_cat\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alphaomegadetailing.gr\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/alphaomegadetailing.gr\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/alphaomegadetailing.gr\/en\/wp-json\/wp\/v2\/product?product_cat=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}